{"id":47,"date":"2021-02-17T17:31:20","date_gmt":"2021-02-17T08:31:20","guid":{"rendered":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/?post_type=trip&#038;p=47"},"modified":"2022-08-26T11:29:41","modified_gmt":"2022-08-26T02:29:41","slug":"nakanoshima-childrens-book-forest","status":"publish","type":"trip","link":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/","title":{"rendered":"Nakanoshima Children&#8217;s Book Forest"},"featured_media":1381,"template":"","architect":[7],"prefectures":[8],"jp_word":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nakanoshima Children&#039;s Book Forest - Virtual Tour of Japanese Architecture - Archi Designer JAPAN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nakanoshima Children&#039;s Book Forest - Virtual Tour of Japanese Architecture - Archi Designer JAPAN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/\" \/>\n<meta property=\"og:site_name\" content=\"Archi Designer JAPAN\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-26T02:29:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-content\/uploads\/2021\/07\/nakanoshima-childrens-book-forest01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/\",\"url\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/\",\"name\":\"Nakanoshima Children's Book Forest - Virtual Tour of Japanese Architecture - Archi Designer JAPAN\",\"isPartOf\":{\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#website\"},\"datePublished\":\"2021-02-17T08:31:20+00:00\",\"dateModified\":\"2022-08-26T02:29:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tour\",\"item\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nakanoshima Children&#8217;s Book Forest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#website\",\"url\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/\",\"name\":\"Archi Designer JAPAN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#organization\",\"name\":\"\u30e1\u30ac\u30bd\u30d5\u30c8\u682a\u5f0f\u4f1a\u793e\",\"url\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-content\/uploads\/2021\/03\/logo-1.png\",\"contentUrl\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-content\/uploads\/2021\/03\/logo-1.png\",\"width\":341,\"height\":132,\"caption\":\"\u30e1\u30ac\u30bd\u30d5\u30c8\u682a\u5f0f\u4f1a\u793e\"},\"image\":{\"@id\":\"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nakanoshima Children's Book Forest - Virtual Tour of Japanese Architecture - Archi Designer JAPAN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/","og_locale":"en_US","og_type":"article","og_title":"Nakanoshima Children's Book Forest - Virtual Tour of Japanese Architecture - Archi Designer JAPAN","og_url":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/","og_site_name":"Archi Designer JAPAN","article_modified_time":"2022-08-26T02:29:41+00:00","og_image":[{"width":680,"height":680,"url":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-content\/uploads\/2021\/07\/nakanoshima-childrens-book-forest01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/","url":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/","name":"Nakanoshima Children's Book Forest - Virtual Tour of Japanese Architecture - Archi Designer JAPAN","isPartOf":{"@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#website"},"datePublished":"2021-02-17T08:31:20+00:00","dateModified":"2022-08-26T02:29:41+00:00","breadcrumb":{"@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/nakanoshima-childrens-book-forest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/"},{"@type":"ListItem","position":2,"name":"tour","item":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/tour\/"},{"@type":"ListItem","position":3,"name":"Nakanoshima Children&#8217;s Book Forest"}]},{"@type":"WebSite","@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#website","url":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/","name":"Archi Designer JAPAN","description":"","publisher":{"@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#organization","name":"\u30e1\u30ac\u30bd\u30d5\u30c8\u682a\u5f0f\u4f1a\u793e","url":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#\/schema\/logo\/image\/","url":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-content\/uploads\/2021\/03\/logo-1.png","contentUrl":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-content\/uploads\/2021\/03\/logo-1.png","width":341,"height":132,"caption":"\u30e1\u30ac\u30bd\u30d5\u30c8\u682a\u5f0f\u4f1a\u793e"},"image":{"@id":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/trip\/47"}],"collection":[{"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/trip"}],"about":[{"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/types\/trip"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/media\/1381"}],"wp:attachment":[{"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"architect","embeddable":true,"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/architect?post=47"},{"taxonomy":"prefectures","embeddable":true,"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/prefectures?post=47"},{"taxonomy":"jp_word","embeddable":true,"href":"https:\/\/www.3darchidesigner.com\/archidesignerjp\/wp-json\/wp\/v2\/jp_word?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}